{"id":653,"date":"2020-11-24T12:43:25","date_gmt":"2020-11-24T11:43:25","guid":{"rendered":"http:\/\/www.parrocchiadisantandrea.it\/psa\/?p=653"},"modified":"2020-11-24T12:43:25","modified_gmt":"2020-11-24T11:43:25","slug":"2020nov-nuovo-messale","status":"publish","type":"post","link":"https:\/\/www.parrocchiadisantandrea.it\/psa\/2020nov-nuovo-messale\/","title":{"rendered":"2020\/Nov &#8211; Nuovo Messale"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large alignleft\" src=\"https:\/\/img.libreriadelsanto.it\/books\/r\/REniLqFUuOcy_s4-mb.jpg\" width=\"255\" height=\"255\">Con la Prima Domenica di Avvento le Diocesi del Triveneto adotteranno il nuovo <strong>Messale<\/strong> (il libro che usa il sacerdote sull\u2019altare per celebrare la messa)<br \/>\nAlcune righe tratte da un articolo di Goffredo Boselli apparso sulla Rivista del Clero Italiano: &#8220;Con la rugiada del tuo Spirito&#8221;. La nuova edizione italiana del Messale Romano. (Marzo 2020)<br \/>\nIl 26 marzo del 1970 Papa Paolo VI pubblicava il Messale, primo frutto tangibile della riforma liturgica del Concilio Vaticano II e, in una certa misura, sintesi dell\u2019intero suo messaggio. Si sono poi succedute due edizioni: quella del 1973 che si limita alla traduzione del latino senza alcun adattamento; e quella del 1983, in uso fino ad ora, e che si arricchisce di molti testi composti direttamente in italiano.<br \/>\nOra, esattamente a cinquant\u2019anni dalla sua pubblicazione, la Chiesa in Italia ha scelto di presentare la nuova edizione del Messale romano e che rappresenta un\u2019immagine fedele del cammino percorso dal rinnovamento liturgico nel nostro Paese. Al tempo stesso, \u00e8 lo specchio del valore e dell\u2019importanza che la nostra Chiesa oggi effettivamente riconosce alla liturgia nella vita delle comunit\u00e0 e in quella di ogni donna e uomo credente, cos\u00ec come del ruolo della liturgia nell\u2019evangelizzazione. Se la liturgia \u00e8 davvero Vangelo celebrato, il modo con il quale la Chiesa celebra il Vangelo rivela la coscienza e la pertinenza con le quali essa lo annuncia, dal momento che la Chiesa evangelizza come celebra e celebra come evangelizza.<br \/>\nIn attesa di poter offrire ai parrocchiani interessati un incontro per meglio conoscere la ricchezza di questo nuovo messale, nel foglietto della prossima settimana troverete le indicazioni su alcune variazioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la Prima Domenica di Avvento le Diocesi del Triveneto adotteranno il nuovo Messale (il libro che usa il sacerdote sull\u2019altare per celebrare la messa) Alcune righe tratte da un articolo di Goffredo Boselli apparso sulla Rivista del Clero Italiano: &#8220;Con la rugiada del tuo Spirito&#8221;. La nuova edizione italiana del Messale Romano. (Marzo 2020) &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.parrocchiadisantandrea.it\/psa\/2020nov-nuovo-messale\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;2020\/Nov &#8211; Nuovo Messale&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/posts\/653"}],"collection":[{"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/comments?post=653"}],"version-history":[{"count":0,"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/posts\/653\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/media?parent=653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/categories?post=653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/tags?post=653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}