{"id":212,"date":"2017-12-11T17:24:42","date_gmt":"2017-12-11T16:24:42","guid":{"rendered":"http:\/\/www.parrocchiadisantandrea.it\/psa\/?p=212"},"modified":"2017-12-11T17:27:18","modified_gmt":"2017-12-11T16:27:18","slug":"2017-dic-natale-nel-mondo-2017","status":"publish","type":"post","link":"https:\/\/www.parrocchiadisantandrea.it\/psa\/2017-dic-natale-nel-mondo-2017\/","title":{"rendered":"2017\/ Dic.- Natale nel mondo 2017"},"content":{"rendered":"<p><em>Pordenone, Domenica 10 dicembre. <\/em>Alle ore 15.00 presso Casa Madonna Pellegrina a Pordenone, organizzata dalla Commissione Diocesana Migrantes, in collaborazione con Fondazione Buon Samaritano &#8211; Casa Madonna Pellegrina &#8211; XXVI Festival Internazionale di Musica Sacra &#8211; Presenza e cultura Pordenone , si \u00e8 svolta una rassegna di canti&nbsp;natalizi filippini, ghanesi, italiano, nigeriano, polacchi, rumeni e ucraini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pordenone, Domenica 10 dicembre. Alle ore 15.00 presso Casa Madonna Pellegrina a Pordenone, organizzata dalla Commissione Diocesana Migrantes, in collaborazione con Fondazione Buon Samaritano &#8211; Casa Madonna Pellegrina &#8211; XXVI Festival Internazionale di Musica Sacra &#8211; Presenza e cultura Pordenone , si \u00e8 svolta una rassegna di canti&nbsp;natalizi filippini, ghanesi, italiano, nigeriano, polacchi, rumeni e &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.parrocchiadisantandrea.it\/psa\/2017-dic-natale-nel-mondo-2017\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;2017\/ Dic.- Natale nel mondo 2017&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/posts\/212"}],"collection":[{"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/comments?post=212"}],"version-history":[{"count":0,"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/posts\/212\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/media?parent=212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/categories?post=212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.parrocchiadisantandrea.it\/psa\/wp-json\/wp\/v2\/tags?post=212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}